{"id":445,"count":3,"description":"Nautic-Produkte f\u00fcr Wasser, Boot &amp; Wassersport stehen f\u00fcr Schutz, Pflege und Werterhalt unter extremen Bedingungen wie Salz, Sonne, Feuchtigkeit und Schmutz. Ob f\u00fcr Boot, Segel, Zubeh\u00f6r oder Ausr\u00fcstung \u2013 mit den richtigen Produkten bleibt alles funktionsf\u00e4hig, sicher und langlebig.\r\nIn dieser Kategorie finden Sie professionelle Nautic-Produkte f\u00fcr Pflege, Schutz und Reinigung im maritimen Bereich.","link":"https:\/\/heba-sport-tec.ch\/it\/categoria-prodotto\/pflegeundreinigung\/nautic-pflegeundreinigung\/","name":"Nautic","slug":"nautic-pflegeundreinigung","taxonomy":"product_cat","parent":420,"meta":[],"acf":[],"_links":{"self":[{"href":"https:\/\/heba-sport-tec.ch\/it\/wp-json\/wp\/v2\/product_cat\/445","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/heba-sport-tec.ch\/it\/wp-json\/wp\/v2\/product_cat"}],"about":[{"href":"https:\/\/heba-sport-tec.ch\/it\/wp-json\/wp\/v2\/taxonomies\/product_cat"}],"up":[{"embeddable":true,"href":"https:\/\/heba-sport-tec.ch\/it\/wp-json\/wp\/v2\/product_cat\/420"}],"wp:post_type":[{"href":"https:\/\/heba-sport-tec.ch\/it\/wp-json\/wp\/v2\/product?product_cat=445"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}