{"id":357,"count":9,"description":"Belagb\u00fcrsten f\u00fcr Ski &amp; Snowboard sind ein zentrales Werkzeug f\u00fcr die professionelle Belagpflege und das perfekte Wachsfinish. Ob oval, Rosshaar, Nylon oder Metall \u2013 jede B\u00fcrste erf\u00fcllt einen speziellen Zweck im Wachsvorgang.\r\nIn dieser Kategorie finden Sie hochwertige Belagb\u00fcrsten f\u00fcr Werkstatt, Skiservice, Rennservice und ambitionierte Hobbysportler.","link":"https:\/\/heba-sport-tec.ch\/it\/categoria-prodotto\/waxandtools\/belag-waxandtools\/buersten-belag-waxandtools\/buersten-oval-buersten-belag-waxandtools\/","name":"B\u00fcrsten Oval","slug":"buersten-oval-buersten-belag-waxandtools","taxonomy":"product_cat","parent":369,"meta":[],"acf":[],"_links":{"self":[{"href":"https:\/\/heba-sport-tec.ch\/it\/wp-json\/wp\/v2\/product_cat\/357","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/heba-sport-tec.ch\/it\/wp-json\/wp\/v2\/product_cat"}],"about":[{"href":"https:\/\/heba-sport-tec.ch\/it\/wp-json\/wp\/v2\/taxonomies\/product_cat"}],"up":[{"embeddable":true,"href":"https:\/\/heba-sport-tec.ch\/it\/wp-json\/wp\/v2\/product_cat\/369"}],"wp:post_type":[{"href":"https:\/\/heba-sport-tec.ch\/it\/wp-json\/wp\/v2\/product?product_cat=357"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}