{"id":328,"count":1,"description":"Ges\u00e4sscreme f\u00fcr Sport &amp; Ausdauerbelastung sch\u00fctzt zuverl\u00e4ssig vor Wundscheuern, Reibung, Hautreizungen und Druckstellen bei langen Belastungen. Besonders beim Biken, Langlaufen, Rennradfahren, Skitourengehen und Ausdauersport sorgt sie f\u00fcr Komfort, Schutz und Leistungsf\u00e4higkeit.\r\nIn dieser Kategorie finden Sie hochwertige Ges\u00e4sscremes f\u00fcr Sportler, Profis und ambitionierte Hobbysportler.","link":"https:\/\/heba-sport-tec.ch\/it\/categoria-prodotto\/pflegeundreinigung\/koerper-pflegeundreinigung\/gesaesscreme\/","name":"Ges\u00e4sscreme","slug":"gesaesscreme","taxonomy":"product_cat","parent":428,"meta":[],"acf":[],"_links":{"self":[{"href":"https:\/\/heba-sport-tec.ch\/it\/wp-json\/wp\/v2\/product_cat\/328","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/heba-sport-tec.ch\/it\/wp-json\/wp\/v2\/product_cat"}],"about":[{"href":"https:\/\/heba-sport-tec.ch\/it\/wp-json\/wp\/v2\/taxonomies\/product_cat"}],"up":[{"embeddable":true,"href":"https:\/\/heba-sport-tec.ch\/it\/wp-json\/wp\/v2\/product_cat\/428"}],"wp:post_type":[{"href":"https:\/\/heba-sport-tec.ch\/it\/wp-json\/wp\/v2\/product?product_cat=328"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}