{"id":296,"count":30,"description":"Feilen f\u00fcr Ski &amp; Snowboard sind das wichtigste Werkzeug f\u00fcr die pr\u00e4zise Kantenbearbeitung und das Sch\u00e4rfen der Stahlkanten. Sie erm\u00f6glichen exakte Winkel, sauberen Materialabtrag und perfekte Kontrolle auf Schnee und Eis.\r\nIn dieser Kategorie finden Sie hochwertige Feilen f\u00fcr Skiservice, Rennservice, Werkstatt und ambitionierte Hobbysportler.","link":"https:\/\/heba-sport-tec.ch\/it\/categoria-prodotto\/waxandtools\/kanten-waxandtools\/feilen-kanten-waxandtools\/","name":"Feilen","slug":"feilen-kanten-waxandtools","taxonomy":"product_cat","parent":293,"meta":[],"acf":[],"_links":{"self":[{"href":"https:\/\/heba-sport-tec.ch\/it\/wp-json\/wp\/v2\/product_cat\/296","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/heba-sport-tec.ch\/it\/wp-json\/wp\/v2\/product_cat"}],"about":[{"href":"https:\/\/heba-sport-tec.ch\/it\/wp-json\/wp\/v2\/taxonomies\/product_cat"}],"up":[{"embeddable":true,"href":"https:\/\/heba-sport-tec.ch\/it\/wp-json\/wp\/v2\/product_cat\/293"}],"wp:post_type":[{"href":"https:\/\/heba-sport-tec.ch\/it\/wp-json\/wp\/v2\/product?product_cat=296"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}