{"id":291,"count":1,"description":"D\u00fcbel &amp; Schrauben f\u00fcr Ski &amp; Snowboard sind essenziell f\u00fcr die sichere und dauerhafte Montage von Skibindungen sowie f\u00fcr Reparaturen im Skiservice. Sie sorgen f\u00fcr stabile Befestigung, optimale Haltekraft und maximale Sicherheit auf der Piste.\r\nIn dieser Kategorie finden Sie hochwertige D\u00fcbel und Schrauben f\u00fcr Werkstatt, Skiservice, Rennservice und Sportfachhandel.","link":"https:\/\/heba-sport-tec.ch\/it\/categoria-prodotto\/waxandtools\/werkstatt-waxandtools\/duebelschrauben\/","name":"D\u00fcbel &amp; Schrauben","slug":"duebelschrauben","taxonomy":"product_cat","parent":431,"meta":[],"acf":[],"_links":{"self":[{"href":"https:\/\/heba-sport-tec.ch\/it\/wp-json\/wp\/v2\/product_cat\/291","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/heba-sport-tec.ch\/it\/wp-json\/wp\/v2\/product_cat"}],"about":[{"href":"https:\/\/heba-sport-tec.ch\/it\/wp-json\/wp\/v2\/taxonomies\/product_cat"}],"up":[{"embeddable":true,"href":"https:\/\/heba-sport-tec.ch\/it\/wp-json\/wp\/v2\/product_cat\/431"}],"wp:post_type":[{"href":"https:\/\/heba-sport-tec.ch\/it\/wp-json\/wp\/v2\/product?product_cat=291"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}