{"id":5731,"date":"2025-11-24T22:22:31","date_gmt":"2025-11-24T22:22:31","guid":{"rendered":"https:\/\/heba-sport-tec.ch\/produkt\/race-cool-wax-12-to-4c\/"},"modified":"2025-11-24T23:15:24","modified_gmt":"2025-11-24T23:15:24","slug":"race-cool-wax-12-to-4c","status":"publish","type":"product","link":"https:\/\/heba-sport-tec.ch\/it\/prodotto\/race-cool-wax-12-to-4c\/","title":{"rendered":"RACE Cool Wax         | -12 to -4C"},"content":{"rendered":"<p>Race-Wachs mit maximaler Geschwindigkeit, Haltbarkeit und Umweltvertr\u00e4glichkeit Unser Race-Wachs liefert herausragende Geschwindigkeit, Langlebigkeit und eine erstklassige Gleitperformance \u2013 und ist dabei vollst\u00e4ndig umweltfreundlich sowie biologisch abbaubar. PROPRI\u00c4R &amp; INNOVATIV Hergestellt mit der exklusiven Ceramic Nanotechnology von mountainFLOW f\u00fcr h\u00f6chste Performance unter Rennbedingungen. UMWELTSICHER 100 % pflanzenbasiert, fluorfrei und frei von Schadstoffen \u2013 eine nachhaltige Alternative zu herk\u00f6mmlichen Rennwachsen. OPTIMIERTE FORMEL Intensiv getestet und genauso schnell wie jedes herk\u00f6mmliche, nicht-fluorierte Race-Wachs \u2013 bei deutlich besserer Umweltbilanz.<\/p>","protected":false},"excerpt":{"rendered":"<p>40 Grams<\/p>","protected":false},"featured_media":5772,"template":"","meta":[],"product_brand":[480],"product_cat":[362],"product_tag":[],"class_list":{"0":"post-5731","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_brand-mountain-flow","7":"product_cat-racing-alpine-wax-waxandtools","9":"first","10":"instock","11":"taxable","12":"shipping-taxable","13":"purchasable","14":"product-type-simple"},"acf":[],"_links":{"self":[{"href":"https:\/\/heba-sport-tec.ch\/it\/wp-json\/wp\/v2\/product\/5731","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/heba-sport-tec.ch\/it\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/heba-sport-tec.ch\/it\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/heba-sport-tec.ch\/it\/wp-json\/wp\/v2\/media\/5772"}],"wp:attachment":[{"href":"https:\/\/heba-sport-tec.ch\/it\/wp-json\/wp\/v2\/media?parent=5731"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/heba-sport-tec.ch\/it\/wp-json\/wp\/v2\/product_brand?post=5731"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/heba-sport-tec.ch\/it\/wp-json\/wp\/v2\/product_cat?post=5731"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/heba-sport-tec.ch\/it\/wp-json\/wp\/v2\/product_tag?post=5731"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}