{"id":2316,"date":"2025-06-05T01:08:52","date_gmt":"2025-06-05T01:08:52","guid":{"rendered":"https:\/\/heba-sport-tec.ch\/produkt\/semi-edger\/"},"modified":"2025-11-19T12:55:55","modified_gmt":"2025-11-19T12:55:55","slug":"semi-edger","status":"publish","type":"product","link":"https:\/\/heba-sport-tec.ch\/it\/prodotto\/semi-edger\/","title":{"rendered":"Semi Edger"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"<p>Semi Edger<br \/>\nSehr hochwertiger, ergonomischer Kantensch\u00e4rfer mit belagsseitigen Gleitfl\u00e4chen.<br \/>\n\u2013   Schleifwinkel einstellbar von 90\u00b0 bis 85\u00b0<br \/>\n\u2013   Geeignet f\u00fcr alle Skifeilen, Schleifdiamanten und Oxydstein   (siehe Seite 54-56)<br \/>\n\u2013   Inkl. hochwertiger 80 mm Feile <\/p>","protected":false},"featured_media":453,"template":"","meta":[],"product_brand":[248],"product_cat":[353,466],"product_tag":[],"class_list":{"0":"post-2316","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_brand-holmenkol","7":"product_cat-feilenhalter-kanten-waxandtools","8":"product_cat-holmenkol","10":"first","11":"instock","12":"taxable","13":"shipping-taxable","14":"purchasable","15":"product-type-simple"},"acf":[],"_links":{"self":[{"href":"https:\/\/heba-sport-tec.ch\/it\/wp-json\/wp\/v2\/product\/2316","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/heba-sport-tec.ch\/it\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/heba-sport-tec.ch\/it\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/heba-sport-tec.ch\/it\/wp-json\/wp\/v2\/media\/453"}],"wp:attachment":[{"href":"https:\/\/heba-sport-tec.ch\/it\/wp-json\/wp\/v2\/media?parent=2316"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/heba-sport-tec.ch\/it\/wp-json\/wp\/v2\/product_brand?post=2316"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/heba-sport-tec.ch\/it\/wp-json\/wp\/v2\/product_cat?post=2316"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/heba-sport-tec.ch\/it\/wp-json\/wp\/v2\/product_tag?post=2316"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}